{"id":3528,"date":"2019-05-19T10:04:11","date_gmt":"2019-05-19T09:04:11","guid":{"rendered":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg"},"modified":"2019-05-19T10:04:11","modified_gmt":"2019-05-19T09:04:11","slug":"casa-guardiola-2","status":"inherit","type":"attachment","link":"https:\/\/casadelpoeta.es\/en\/palace-houses-seville\/casa-guardiola-2\/","title":{"rendered":"casa-guardiola"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-3528","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>casa-guardiola - Hotel Boutique en el centro de Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"casa-guardiola - Hotel Boutique en el centro de Sevilla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Boutique en el centro de Sevilla\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadelpoeta.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/casa-guardiola.jpg\",\"url\":\"https:\\\/\\\/casadelpoeta.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/casa-guardiola.jpg\",\"name\":\"casa-guardiola - Hotel Boutique en el centro de Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadelpoeta.es\\\/#website\"},\"datePublished\":\"2019-05-19T09:04:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadelpoeta.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/casa-guardiola.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadelpoeta.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/casa-guardiola.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadelpoeta.es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/casa-guardiola.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/casadelpoeta.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The palace houses and the hidden treasures of Seville\",\"item\":\"https:\\\/\\\/casadelpoeta.es\\\/en\\\/palace-houses-seville\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"casa-guardiola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadelpoeta.es\\\/#website\",\"url\":\"https:\\\/\\\/casadelpoeta.es\\\/\",\"name\":\"Hotel Boutique en el centro de Sevilla\",\"description\":\"Casa del Poeta es un Hotel Boutique ubiccado en el Barrio de Santa Cruz, en pleno centro de Sevilla, Hotel con encanto con patio sevillano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadelpoeta.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"casa-guardiola - Hotel Boutique en el centro de Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg","og_locale":"en_US","og_type":"article","og_title":"casa-guardiola - Hotel Boutique en el centro de Sevilla","og_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg","og_site_name":"Hotel Boutique en el centro de Sevilla","og_image":[{"width":550,"height":484,"url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg","url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg","name":"casa-guardiola - Hotel Boutique en el centro de Sevilla","isPartOf":{"@id":"https:\/\/casadelpoeta.es\/#website"},"datePublished":"2019-05-19T09:04:11+00:00","breadcrumb":{"@id":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casadelpoeta.es\/en\/"},{"@type":"ListItem","position":2,"name":"The palace houses and the hidden treasures of Seville","item":"https:\/\/casadelpoeta.es\/en\/palace-houses-seville\/"},{"@type":"ListItem","position":3,"name":"casa-guardiola"}]},{"@type":"WebSite","@id":"https:\/\/casadelpoeta.es\/#website","url":"https:\/\/casadelpoeta.es\/","name":"Hotel Boutique en el centro de Sevilla","description":"Casa del Poeta es un Hotel Boutique ubiccado en el Barrio de Santa Cruz, en pleno centro de Sevilla, Hotel con encanto con patio sevillano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadelpoeta.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"264\" src=\"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-300x264.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-300x264.jpg 300w, https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":550,"height":484,"file":"2019\/05\/casa-guardiola.jpg","sizes":{"thumbnail":{"file":"casa-guardiola-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-150x150.jpg"},"medium":{"file":"casa-guardiola-300x264.jpg","width":300,"height":264,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-300x264.jpg"},"menu-featured-post":{"file":"casa-guardiola-345x198.jpg","width":345,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-345x198.jpg"},"qode-carousel_slider":{"file":"casa-guardiola-400x260.jpg","width":400,"height":260,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-400x260.jpg"},"portfolio_slider":{"file":"casa-guardiola-500x380.jpg","width":500,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-500x380.jpg"},"portfolio_masonry_regular":{"file":"casa-guardiola-500x484.jpg","width":500,"height":484,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-500x484.jpg"},"portfolio_masonry_tall":{"file":"casa-guardiola-500x484.jpg","width":500,"height":484,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-500x484.jpg"},"latest_post_boxes":{"file":"casa-guardiola-539x303.jpg","width":539,"height":303,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola-539x303.jpg"},"full":{"file":"casa-guardiola.jpg","width":550,"height":484,"mime_type":"image\/jpeg","source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3547,"source_url":"https:\/\/casadelpoeta.es\/wp-content\/uploads\/2019\/05\/casa-guardiola.jpg","_links":{"self":[{"href":"https:\/\/casadelpoeta.es\/en\/wp-json\/wp\/v2\/media\/3528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadelpoeta.es\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/casadelpoeta.es\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/casadelpoeta.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casadelpoeta.es\/en\/wp-json\/wp\/v2\/comments?post=3528"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3547,"href":"https:\/\/casadelpoeta.es\/en\/wp-json\/wp\/v2\/posts\/3547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}